{"id":7317,"date":"2020-11-26T18:52:42","date_gmt":"2020-11-26T21:52:42","guid":{"rendered":"http:\/\/diarioprincipios.com\/?p=7317"},"modified":"2020-11-26T18:54:08","modified_gmt":"2020-11-26T21:54:08","slug":"mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona","status":"publish","type":"post","link":"https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/","title":{"rendered":"Mussi anunci\u00f3 que la calle 63 (camino al r\u00edo) se llamar\u00e1 Diego Armando Maradona"},"content":{"rendered":"\n<p>Hace escasos minutos, a trav\u00e9s de sus redes sociales, el Intendente de Berazategui, doctor Juan Jos\u00e9 Mussi anunci\u00f3 que \u00abla calle 63 (camino al r\u00edo) se llamar\u00e1 Diego Armando Maradona, en honor al mejor futbolista de la historia de nuestro pa\u00eds y del mundo!\u00bb.<\/p>\n\n\n\n<p>El jefe comunal escribi\u00f3 adem\u00e1s \u00bb Gracias por la alegr\u00eda que nos diste con tu magia a tantos berazateguenses! \ud83e\udde1 Que en paz descanses, compa\u00f1ero! #Berazategui #BerazateguiCorazonDeZonaSur\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace escasos minutos, a trav\u00e9s de sus redes sociales, el Intendente de Berazategui, doctor Juan Jos\u00e9 Mussi anunci\u00f3 que \u00abla calle 63 (camino al r\u00edo) se llamar\u00e1 Diego Armando Maradona, en honor al mejor futbolista de la historia de nuestro pa\u00eds y del mundo!\u00bb. El jefe comunal escribi\u00f3 adem\u00e1s \u00bb Gracias por la alegr\u00eda que&#8230;<\/p>\n","protected":false},"author":2,"featured_media":7318,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-7317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-berazategui"],"featured_image_src":"https:\/\/diarioprincipios.com\/wp-content\/uploads\/2020\/11\/FB_IMG_1606427348419.jpg","blog_images":{"medium":"https:\/\/diarioprincipios.com\/wp-content\/uploads\/2020\/11\/FB_IMG_1606427348419-300x300.jpg","large":"https:\/\/diarioprincipios.com\/wp-content\/uploads\/2020\/11\/FB_IMG_1606427348419.jpg"},"ams_acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mussi anunci\u00f3 que la calle 63 (camino al r\u00edo) se llamar\u00e1 Diego Armando Maradona - Principios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mussi anunci\u00f3 que la calle 63 (camino al r\u00edo) se llamar\u00e1 Diego Armando Maradona - Principios\" \/>\n<meta property=\"og:description\" content=\"Hace escasos minutos, a trav\u00e9s de sus redes sociales, el Intendente de Berazategui, doctor Juan Jos\u00e9 Mussi anunci\u00f3 que \u00abla calle 63 (camino al r\u00edo) se llamar\u00e1 Diego Armando Maradona, en honor al mejor futbolista de la historia de nuestro pa\u00eds y del mundo!\u00bb. El jefe comunal escribi\u00f3 adem\u00e1s \u00bb Gracias por la alegr\u00eda que...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/\" \/>\n<meta property=\"og:site_name\" content=\"Principios\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-26T21:52:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-26T21:54:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioprincipios.com\/wp-content\/uploads\/2020\/11\/FB_IMG_1606427348419.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"912\" \/>\n\t<meta property=\"og:image:height\" content=\"912\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hern\u00e1n L\u00f3pez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hern\u00e1n L\u00f3pez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/index.php\\\/2020\\\/11\\\/26\\\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/index.php\\\/2020\\\/11\\\/26\\\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\\\/\"},\"author\":{\"name\":\"Hern\u00e1n L\u00f3pez\",\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/#\\\/schema\\\/person\\\/436d5a1fd41a5e250e23ff5a6a7cb080\"},\"headline\":\"Mussi anunci\u00f3 que la calle 63 (camino al r\u00edo) se llamar\u00e1 Diego Armando Maradona\",\"datePublished\":\"2020-11-26T21:52:42+00:00\",\"dateModified\":\"2020-11-26T21:54:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/index.php\\\/2020\\\/11\\\/26\\\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\\\/\"},\"wordCount\":88,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/index.php\\\/2020\\\/11\\\/26\\\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diarioprincipios.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/FB_IMG_1606427348419.jpg\",\"articleSection\":[\"Berazategui\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diarioprincipios.com\\\/index.php\\\/2020\\\/11\\\/26\\\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/index.php\\\/2020\\\/11\\\/26\\\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\\\/\",\"url\":\"https:\\\/\\\/diarioprincipios.com\\\/index.php\\\/2020\\\/11\\\/26\\\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\\\/\",\"name\":\"Mussi anunci\u00f3 que la calle 63 (camino al r\u00edo) se llamar\u00e1 Diego Armando Maradona - Principios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/index.php\\\/2020\\\/11\\\/26\\\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/index.php\\\/2020\\\/11\\\/26\\\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diarioprincipios.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/FB_IMG_1606427348419.jpg\",\"datePublished\":\"2020-11-26T21:52:42+00:00\",\"dateModified\":\"2020-11-26T21:54:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/index.php\\\/2020\\\/11\\\/26\\\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diarioprincipios.com\\\/index.php\\\/2020\\\/11\\\/26\\\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/index.php\\\/2020\\\/11\\\/26\\\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diarioprincipios.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/FB_IMG_1606427348419.jpg\",\"contentUrl\":\"https:\\\/\\\/diarioprincipios.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/FB_IMG_1606427348419.jpg\",\"width\":912,\"height\":912},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/index.php\\\/2020\\\/11\\\/26\\\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diarioprincipios.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mussi anunci\u00f3 que la calle 63 (camino al r\u00edo) se llamar\u00e1 Diego Armando Maradona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/#website\",\"url\":\"https:\\\/\\\/diarioprincipios.com\\\/\",\"name\":\"Principios\",\"description\":\"Principios Diario\",\"publisher\":{\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diarioprincipios.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/#organization\",\"name\":\"Principios\",\"url\":\"https:\\\/\\\/diarioprincipios.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diarioprincipios.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-www.diarioprincipios.com_-1.png\",\"contentUrl\":\"https:\\\/\\\/diarioprincipios.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-www.diarioprincipios.com_-1.png\",\"width\":5325,\"height\":1454,\"caption\":\"Principios\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/#\\\/schema\\\/person\\\/436d5a1fd41a5e250e23ff5a6a7cb080\",\"name\":\"Hern\u00e1n L\u00f3pez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diarioprincipios.com\\\/wp-content\\\/litespeed\\\/avatar\\\/11ddfe5610ff3bd100522525b2571f48.jpg?ver=1778258056\",\"url\":\"https:\\\/\\\/diarioprincipios.com\\\/wp-content\\\/litespeed\\\/avatar\\\/11ddfe5610ff3bd100522525b2571f48.jpg?ver=1778258056\",\"contentUrl\":\"https:\\\/\\\/diarioprincipios.com\\\/wp-content\\\/litespeed\\\/avatar\\\/11ddfe5610ff3bd100522525b2571f48.jpg?ver=1778258056\",\"caption\":\"Hern\u00e1n L\u00f3pez\"},\"url\":\"https:\\\/\\\/diarioprincipios.com\\\/index.php\\\/author\\\/hernan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mussi anunci\u00f3 que la calle 63 (camino al r\u00edo) se llamar\u00e1 Diego Armando Maradona - Principios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/","og_locale":"es_ES","og_type":"article","og_title":"Mussi anunci\u00f3 que la calle 63 (camino al r\u00edo) se llamar\u00e1 Diego Armando Maradona - Principios","og_description":"Hace escasos minutos, a trav\u00e9s de sus redes sociales, el Intendente de Berazategui, doctor Juan Jos\u00e9 Mussi anunci\u00f3 que \u00abla calle 63 (camino al r\u00edo) se llamar\u00e1 Diego Armando Maradona, en honor al mejor futbolista de la historia de nuestro pa\u00eds y del mundo!\u00bb. El jefe comunal escribi\u00f3 adem\u00e1s \u00bb Gracias por la alegr\u00eda que...","og_url":"https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/","og_site_name":"Principios","article_published_time":"2020-11-26T21:52:42+00:00","article_modified_time":"2020-11-26T21:54:08+00:00","og_image":[{"width":912,"height":912,"url":"https:\/\/diarioprincipios.com\/wp-content\/uploads\/2020\/11\/FB_IMG_1606427348419.jpg","type":"image\/jpeg"}],"author":"Hern\u00e1n L\u00f3pez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Hern\u00e1n L\u00f3pez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/#article","isPartOf":{"@id":"https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/"},"author":{"name":"Hern\u00e1n L\u00f3pez","@id":"https:\/\/diarioprincipios.com\/#\/schema\/person\/436d5a1fd41a5e250e23ff5a6a7cb080"},"headline":"Mussi anunci\u00f3 que la calle 63 (camino al r\u00edo) se llamar\u00e1 Diego Armando Maradona","datePublished":"2020-11-26T21:52:42+00:00","dateModified":"2020-11-26T21:54:08+00:00","mainEntityOfPage":{"@id":"https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/"},"wordCount":88,"commentCount":0,"publisher":{"@id":"https:\/\/diarioprincipios.com\/#organization"},"image":{"@id":"https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioprincipios.com\/wp-content\/uploads\/2020\/11\/FB_IMG_1606427348419.jpg","articleSection":["Berazategui"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/","url":"https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/","name":"Mussi anunci\u00f3 que la calle 63 (camino al r\u00edo) se llamar\u00e1 Diego Armando Maradona - Principios","isPartOf":{"@id":"https:\/\/diarioprincipios.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/#primaryimage"},"image":{"@id":"https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioprincipios.com\/wp-content\/uploads\/2020\/11\/FB_IMG_1606427348419.jpg","datePublished":"2020-11-26T21:52:42+00:00","dateModified":"2020-11-26T21:54:08+00:00","breadcrumb":{"@id":"https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/#primaryimage","url":"https:\/\/diarioprincipios.com\/wp-content\/uploads\/2020\/11\/FB_IMG_1606427348419.jpg","contentUrl":"https:\/\/diarioprincipios.com\/wp-content\/uploads\/2020\/11\/FB_IMG_1606427348419.jpg","width":912,"height":912},{"@type":"BreadcrumbList","@id":"https:\/\/diarioprincipios.com\/index.php\/2020\/11\/26\/mussi-anuncio-que-la-calle-63-camino-al-rio-se-llamara-diego-armando-maradona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioprincipios.com\/"},{"@type":"ListItem","position":2,"name":"Mussi anunci\u00f3 que la calle 63 (camino al r\u00edo) se llamar\u00e1 Diego Armando Maradona"}]},{"@type":"WebSite","@id":"https:\/\/diarioprincipios.com\/#website","url":"https:\/\/diarioprincipios.com\/","name":"Principios","description":"Principios Diario","publisher":{"@id":"https:\/\/diarioprincipios.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioprincipios.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diarioprincipios.com\/#organization","name":"Principios","url":"https:\/\/diarioprincipios.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioprincipios.com\/#\/schema\/logo\/image\/","url":"https:\/\/diarioprincipios.com\/wp-content\/uploads\/2024\/04\/cropped-www.diarioprincipios.com_-1.png","contentUrl":"https:\/\/diarioprincipios.com\/wp-content\/uploads\/2024\/04\/cropped-www.diarioprincipios.com_-1.png","width":5325,"height":1454,"caption":"Principios"},"image":{"@id":"https:\/\/diarioprincipios.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/diarioprincipios.com\/#\/schema\/person\/436d5a1fd41a5e250e23ff5a6a7cb080","name":"Hern\u00e1n L\u00f3pez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioprincipios.com\/wp-content\/litespeed\/avatar\/11ddfe5610ff3bd100522525b2571f48.jpg?ver=1778258056","url":"https:\/\/diarioprincipios.com\/wp-content\/litespeed\/avatar\/11ddfe5610ff3bd100522525b2571f48.jpg?ver=1778258056","contentUrl":"https:\/\/diarioprincipios.com\/wp-content\/litespeed\/avatar\/11ddfe5610ff3bd100522525b2571f48.jpg?ver=1778258056","caption":"Hern\u00e1n L\u00f3pez"},"url":"https:\/\/diarioprincipios.com\/index.php\/author\/hernan\/"}]}},"jetpack_featured_media_url":"https:\/\/diarioprincipios.com\/wp-content\/uploads\/2020\/11\/FB_IMG_1606427348419.jpg","_links":{"self":[{"href":"https:\/\/diarioprincipios.com\/index.php\/wp-json\/wp\/v2\/posts\/7317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioprincipios.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioprincipios.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioprincipios.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioprincipios.com\/index.php\/wp-json\/wp\/v2\/comments?post=7317"}],"version-history":[{"count":3,"href":"https:\/\/diarioprincipios.com\/index.php\/wp-json\/wp\/v2\/posts\/7317\/revisions"}],"predecessor-version":[{"id":7321,"href":"https:\/\/diarioprincipios.com\/index.php\/wp-json\/wp\/v2\/posts\/7317\/revisions\/7321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioprincipios.com\/index.php\/wp-json\/wp\/v2\/media\/7318"}],"wp:attachment":[{"href":"https:\/\/diarioprincipios.com\/index.php\/wp-json\/wp\/v2\/media?parent=7317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioprincipios.com\/index.php\/wp-json\/wp\/v2\/categories?post=7317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioprincipios.com\/index.php\/wp-json\/wp\/v2\/tags?post=7317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}